{"id":43,"count":1,"description":"","link":"https:\/\/fluorideexposed.org\/facts\/tag\/mae-jemison","name":"Mae Jemison","slug":"mae-jemison","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mae Jemison Archives - Fluoride Exposed<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fluorideexposed.org\/facts\/tag\/mae-jemison\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mae Jemison Archives - Fluoride Exposed\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fluorideexposed.org\/facts\/tag\/mae-jemison\" \/>\n<meta property=\"og:site_name\" content=\"Fluoride Exposed\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/fluorideexposed.org\\\/facts\\\/tag\\\/mae-jemison\",\"url\":\"https:\\\/\\\/fluorideexposed.org\\\/facts\\\/tag\\\/mae-jemison\",\"name\":\"Mae Jemison Archives - Fluoride Exposed\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fluorideexposed.org\\\/facts\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fluorideexposed.org\\\/facts\\\/tag\\\/mae-jemison#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fluorideexposed.org\\\/facts\\\/tag\\\/mae-jemison#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fluorideexposed.org\\\/facts\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mae Jemison\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fluorideexposed.org\\\/facts\\\/#website\",\"url\":\"https:\\\/\\\/fluorideexposed.org\\\/facts\\\/\",\"name\":\"Fluoride Exposed\",\"description\":\"Real Science for Real People\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fluorideexposed.org\\\/facts\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mae Jemison Archives - Fluoride Exposed","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fluorideexposed.org\/facts\/tag\/mae-jemison","og_locale":"en_US","og_type":"article","og_title":"Mae Jemison Archives - Fluoride Exposed","og_url":"https:\/\/fluorideexposed.org\/facts\/tag\/mae-jemison","og_site_name":"Fluoride Exposed","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/fluorideexposed.org\/facts\/tag\/mae-jemison","url":"https:\/\/fluorideexposed.org\/facts\/tag\/mae-jemison","name":"Mae Jemison Archives - Fluoride Exposed","isPartOf":{"@id":"https:\/\/fluorideexposed.org\/facts\/#website"},"breadcrumb":{"@id":"https:\/\/fluorideexposed.org\/facts\/tag\/mae-jemison#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/fluorideexposed.org\/facts\/tag\/mae-jemison#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fluorideexposed.org\/facts\/"},{"@type":"ListItem","position":2,"name":"Mae Jemison"}]},{"@type":"WebSite","@id":"https:\/\/fluorideexposed.org\/facts\/#website","url":"https:\/\/fluorideexposed.org\/facts\/","name":"Fluoride Exposed","description":"Real Science for Real People","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fluorideexposed.org\/facts\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/fluorideexposed.org\/facts\/wp-json\/wp\/v2\/tags\/43","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fluorideexposed.org\/facts\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/fluorideexposed.org\/facts\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/fluorideexposed.org\/facts\/wp-json\/wp\/v2\/posts?tags=43"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}